{"id":1717,"date":"2011-11-08T21:02:19","date_gmt":"2011-11-08T21:02:19","guid":{"rendered":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/?p=1717"},"modified":"2014-10-08T23:10:58","modified_gmt":"2014-10-08T23:10:58","slug":"indian-law-ethics-mini-cle-conference","status":"publish","type":"post","link":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/","title":{"rendered":"Indian Law Ethics Mini CLE Conference"},"content":{"rendered":"<p style=\"text-align: center\"><strong>Indian Law Ethics Mini CLE Conference<\/strong><strong><\/strong><\/p>\n<p><strong>Get your required Professional Responsibility \/ Ethics CLE credits in one short afternoon! \u00a03.0 credits for AZ and CA. \u00a0NM approval pending.<\/strong><\/p>\n<p><strong>Dec 2 &#8211; Noon to 3:15 pm.\u00a0\u00a0 <\/strong><\/p>\n<p style=\"text-align: center\"><strong><strong>Lunch will be provided.<\/strong><br \/>\n<strong>Agenda, speaker information, \u00a0and online registration at\u00a0<a href=\"http:\/\/asu.us1.list-manage.com\/track\/click?u=c82b749211155ebb7cc17b761&amp;id=206c8f246c&amp;e=jcRA0iZ2Q4\">http:\/\/conferences.asucollegeoflaw.com\/indianlawethics\/<\/a><\/strong><br \/>\n<strong>Sandra Day O&#8217;Connor College of Law at Arizona State University, Armstrong Hall, Great Hall<\/strong><br \/>\n<a href=\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/files\/2011\/11\/ILP_Ethics_6501.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1719\" src=\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/files\/2011\/11\/ILP_Ethics_6501.jpg\" alt=\"\" width=\"650\" height=\"841\" srcset=\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/wp-content\/blogs.dir\/9\/files\/sites\/2\/2011\/11\/ILP_Ethics_6501.jpg 650w, http:\/\/newsletters.asucollegeoflaw.com\/ilp\/wp-content\/blogs.dir\/9\/files\/sites\/2\/2011\/11\/ILP_Ethics_6501-231x300.jpg 231w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/a><br \/>\n<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Indian Law Ethics Mini CLE Conference Get your required Professional Responsibility \/ Ethics CLE credits in one short afternoon! \u00a03.0 credits for AZ and CA. \u00a0NM approval pending. Dec 2 &#8211; Noon to 3:15 pm.\u00a0\u00a0 Lunch will be provided. Agenda, &hellip; <a href=\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,1],"tags":[],"class_list":["post-1717","post","type-post","status-publish","format-standard","hentry","category-event","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Indian Law Ethics Mini CLE Conference - Indian Legal Program<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Indian Law Ethics Mini CLE Conference - Indian Legal Program\" \/>\n<meta property=\"og:description\" content=\"Indian Law Ethics Mini CLE Conference Get your required Professional Responsibility \/ Ethics CLE credits in one short afternoon! \u00a03.0 credits for AZ and CA. \u00a0NM approval pending. Dec 2 &#8211; Noon to 3:15 pm.\u00a0\u00a0 Lunch will be provided. Agenda, &hellip; Continue reading &rarr;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/\" \/>\n<meta property=\"og:site_name\" content=\"Indian Legal Program\" \/>\n<meta property=\"article:published_time\" content=\"2011-11-08T21:02:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-10-08T23:10:58+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/files\/2011\/11\/ILP_Ethics_6501.jpg\" \/>\n<meta name=\"author\" content=\"Indian Legal Program\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Indian Legal Program\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/\",\"url\":\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/\",\"name\":\"Indian Law Ethics Mini CLE Conference - Indian Legal Program\",\"isPartOf\":{\"@id\":\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/files\/2011\/11\/ILP_Ethics_6501.jpg\",\"datePublished\":\"2011-11-08T21:02:19+00:00\",\"dateModified\":\"2014-10-08T23:10:58+00:00\",\"author\":{\"@id\":\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/#\/schema\/person\/e936df29158d1ed561630688e0c413ef\"},\"breadcrumb\":{\"@id\":\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/#primaryimage\",\"url\":\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/files\/2011\/11\/ILP_Ethics_6501.jpg\",\"contentUrl\":\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/files\/2011\/11\/ILP_Ethics_6501.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Indian Law Ethics Mini CLE Conference\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/#website\",\"url\":\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/\",\"name\":\"Indian Legal Program\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/#\/schema\/person\/e936df29158d1ed561630688e0c413ef\",\"name\":\"Indian Legal Program\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/62bd2f49621cd65d5dfdee9157966074?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/62bd2f49621cd65d5dfdee9157966074?s=96&d=mm&r=g\",\"caption\":\"Indian Legal Program\"},\"url\":\"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/author\/kitevis\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Indian Law Ethics Mini CLE Conference - Indian Legal Program","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/","og_locale":"en_US","og_type":"article","og_title":"Indian Law Ethics Mini CLE Conference - Indian Legal Program","og_description":"Indian Law Ethics Mini CLE Conference Get your required Professional Responsibility \/ Ethics CLE credits in one short afternoon! \u00a03.0 credits for AZ and CA. \u00a0NM approval pending. Dec 2 &#8211; Noon to 3:15 pm.\u00a0\u00a0 Lunch will be provided. Agenda, &hellip; Continue reading &rarr;","og_url":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/","og_site_name":"Indian Legal Program","article_published_time":"2011-11-08T21:02:19+00:00","article_modified_time":"2014-10-08T23:10:58+00:00","og_image":[{"url":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/files\/2011\/11\/ILP_Ethics_6501.jpg"}],"author":"Indian Legal Program","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Indian Legal Program"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/","url":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/","name":"Indian Law Ethics Mini CLE Conference - Indian Legal Program","isPartOf":{"@id":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/#website"},"primaryImageOfPage":{"@id":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/#primaryimage"},"image":{"@id":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/#primaryimage"},"thumbnailUrl":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/files\/2011\/11\/ILP_Ethics_6501.jpg","datePublished":"2011-11-08T21:02:19+00:00","dateModified":"2014-10-08T23:10:58+00:00","author":{"@id":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/#\/schema\/person\/e936df29158d1ed561630688e0c413ef"},"breadcrumb":{"@id":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/#primaryimage","url":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/files\/2011\/11\/ILP_Ethics_6501.jpg","contentUrl":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/files\/2011\/11\/ILP_Ethics_6501.jpg"},{"@type":"BreadcrumbList","@id":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/2011\/11\/08\/indian-law-ethics-mini-cle-conference\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/"},{"@type":"ListItem","position":2,"name":"Indian Law Ethics Mini CLE Conference"}]},{"@type":"WebSite","@id":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/#website","url":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/","name":"Indian Legal Program","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/#\/schema\/person\/e936df29158d1ed561630688e0c413ef","name":"Indian Legal Program","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/62bd2f49621cd65d5dfdee9157966074?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/62bd2f49621cd65d5dfdee9157966074?s=96&d=mm&r=g","caption":"Indian Legal Program"},"url":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/author\/kitevis\/"}]}},"_links":{"self":[{"href":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/wp-json\/wp\/v2\/posts\/1717"}],"collection":[{"href":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/wp-json\/wp\/v2\/comments?post=1717"}],"version-history":[{"count":5,"href":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/wp-json\/wp\/v2\/posts\/1717\/revisions"}],"predecessor-version":[{"id":4301,"href":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/wp-json\/wp\/v2\/posts\/1717\/revisions\/4301"}],"wp:attachment":[{"href":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/wp-json\/wp\/v2\/media?parent=1717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/wp-json\/wp\/v2\/categories?post=1717"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/newsletters.asucollegeoflaw.com\/ilp\/wp-json\/wp\/v2\/tags?post=1717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}